{"id":11615,"date":"2023-11-22T11:31:52","date_gmt":"2023-11-22T10:31:52","guid":{"rendered":"https:\/\/biosafin.com\/implantologia-winsix-2\/"},"modified":"2023-11-24T11:33:23","modified_gmt":"2023-11-24T10:33:23","slug":"winsix-implantology","status":"publish","type":"page","link":"https:\/\/biosafin.com\/en\/winsix-implantology\/","title":{"rendered":"WINSIX IMPLANTOLOGY"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;11505&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;15%&#8221; top_padding_tablet=&#8221;30%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;30%&#8221; top_padding_phone=&#8221;40%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;40%&#8221; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;radial&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;45%&#8221; bg_image_animation=&#8221;zoom-out&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;0px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;radial&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;center&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; zindex=&#8221;20&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;0px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;A COMPLETE IMPLANT SYSTEM&#8221; animation_delay=&#8221;200&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; text_content=&#8221;Solutions for optimum management of implant-supported prosthetics&#8221; animation_delay=&#8221;200&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3><strong>WINSIX Implant System<\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;accent-color&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15&#8243;][image_with_animation image_url=&#8221;6605&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;20px&#8221; icon_iconsmind=&#8221;iconsmind-Tooth-2&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"color: #99cc00;\">DESIGNED WITH AESTHETICS AND PERFORMANCE IN MIND<br \/>\n<\/span><strong>The WINSIX Implant System<\/strong> offers integrated conventional and digital solutions that are straightforward and intuitive to use, with improved performance in results.Used by dentists since 1995 with different rehabilitation needs for different types of uses and workflows, its evolution has contributed significantly to the development of precise and effective operational protocols<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;20px&#8221; icon_iconsmind=&#8221;iconsmind-Loading-3&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"color: #99cc00;\">CHOOSE THE SOLUTION BEST SUITED TO YOUR CASE<br \/>\n<\/span>The <strong>various implant lines<\/strong> offer a wide choice of connections, implant morphologies and types of apical collar, for optimal management of hard and soft tissues.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;20px&#8221; icon_iconsmind=&#8221;iconsmind-Three-FingersDrag2&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span style=\"color: #99cc00;\">SOLID SCIENTIFIC BASE<\/span><br \/>\nThe <strong>WINSIX implant system<\/strong> is scientifically grounded in the Study and Research conducted since 1995 with the collaboration of world-renowned clinical sites and universities.<br \/>\nThe WINSIX pilot centre is based in the dental department of San Raffaele Hospital in Milan \u2014 the main hub for this activity.<\/p>\n<p><a href=\"https:\/\/biosafin.com\/implantologia-winsix\/\">Sfoglia tutta la Bibliografia WINSIX<\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;20px&#8221; icon_iconsmind=&#8221;iconsmind-Shield&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<p style=\"text-align: left;\"><span style=\"color: #99cc00;\">QUALITY AND SAFETY<\/span><br \/>\nThe <strong>Certified Quality<\/strong> devices, the current state-of-the-art solutions and the competent back office support ensure that dentists have peace of mind today and tomorrow.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;11416&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay=&#8221;#000000&#8243; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.6&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;400&#8243; link_url=&#8221;https:\/\/biosafin.com\/en\/torque-type-implants\/&#8221;]\n<h3><strong>TORQUE TYPE Implants<\/strong><\/h3>\n<p>5 different connections with the same implant body[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;11414&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay=&#8221;#000000&#8243; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.6&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;&#8221; min_height=&#8221;400&#8243; link_url=&#8221;https:\/\/biosafin.com\/en\/k25-implant\/&#8221;]\n<h3><strong>K25 Implants<\/strong><\/h3>\n<h4><strong>The ideal implant for post-extraction and immediate rehabilitation techniques.<\/strong><\/h4>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;11418&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay=&#8221;#000000&#8243; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.6&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;400&#8243; link_url=&#8221;https:\/\/biosafin.com\/en\/kappa-line-implants\/&#8221;]\n<h3><strong>KAPPA Line Implants<\/strong><\/h3>\n<h4><strong>Optimum soft tissue management<\/strong><\/h4>\n[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;11420&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay=&#8221;#000000&#8243; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.6&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;&#8221; min_height=&#8221;400&#8243; link_url=&#8221;https:\/\/biosafin.com\/impianti-slim\/&#8221;]\n<h3><strong>\u00a0SLIM <\/strong><strong>Implants<\/strong><\/h3>\n<h4><strong>diam. 2.9 and 3.3 mm. for thin ridges and space constraints<\/strong><\/h4>\n[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;11422&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay=&#8221;#000000&#8243; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.6&#8243; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; color_scheme=&#8221;dark&#8221; secondary_content=&#8221;here&#8217;s some awesome text that would only be shown on hover&#8221; min_height=&#8221;400&#8243; link_url=&#8221;https:\/\/biosafin.com\/en\/short-implants\/&#8221;]\n<h3><strong>SHORT Implants<\/strong><\/h3>\n<h4><strong>h. 6 mm in case with poor bone availability<\/strong><\/h4>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15&#8243;][vc_column_text]\n<h4><strong>MRS Implant Surface \u2014 Micro-Rough Surface<\/strong><\/h4>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;8222&#8243; background_image_position=&#8221;left center&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8222&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<strong>Since 2005, the MRS surface applies to all Implants in the WINSIX implant System<\/strong>Its reliability offers maximum assurance for implant prosthodontic treatment<\/p>\n<p>The MRS surface has an irregular morphology, obtained by means of the removal processes of sandblasting and acid-etching directly onto the titanium surface of the implant.<\/p>\n<p>Its extensive and well-documented clinical application highlights the optimisation of osseointegration time, aided by the special three-dimensional geometry of the nanostructure and the specific scaffold morphology that fosters the process of osteoconduction.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text]48X enlargement of a TORQUE TYPE implant. MicroRough Surface.[\/vc_column_text][split_line_heading animation_type=&#8221;default&#8221;]\n<h2><strong>WINSIX Surgical and Prosthodontics Kit<\/strong><\/h2>\n[\/split_line_heading][vc_gallery type=&#8221;flickity_static_height_style&#8221; images=&#8221;10715,10719,10717,10725,10729,10733,10727,10721,10723,10731&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;11505&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;15%&#8221; top_padding_tablet=&#8221;30%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;30%&#8221; top_padding_phone=&#8221;40%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;40%&#8221; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;radial&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;45%&#8221; bg_image_animation=&#8221;zoom-out&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221;&hellip; <a class=\"read-more-link\" href=\"https:\/\/biosafin.com\/en\/winsix-implantology\/\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-11615","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/pages\/11615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/comments?post=11615"}],"version-history":[{"count":63,"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/pages\/11615\/revisions"}],"predecessor-version":[{"id":11823,"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/pages\/11615\/revisions\/11823"}],"wp:attachment":[{"href":"https:\/\/biosafin.com\/en\/wp-json\/wp\/v2\/media?parent=11615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}